{"id":3,"count":7,"description":"","link":"https:\/\/rogerrakestraw.com\/index.php\/tag\/mindset\/","name":"Mindset","slug":"mindset","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mindset Archives - Roger&#039;s Site<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rogerrakestraw.com\/index.php\/tag\/mindset\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mindset Archives - Roger&#039;s Site\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rogerrakestraw.com\/index.php\/tag\/mindset\/\" \/>\n<meta property=\"og:site_name\" content=\"Roger&#039;s Site\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/rogerrakestraw.com\\\/index.php\\\/tag\\\/mindset\\\/\",\"url\":\"https:\\\/\\\/rogerrakestraw.com\\\/index.php\\\/tag\\\/mindset\\\/\",\"name\":\"Mindset Archives - Roger&#039;s Site\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rogerrakestraw.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rogerrakestraw.com\\\/index.php\\\/tag\\\/mindset\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rogerrakestraw.com\\\/index.php\\\/tag\\\/mindset\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rogerrakestraw.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mindset\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rogerrakestraw.com\\\/#website\",\"url\":\"https:\\\/\\\/rogerrakestraw.com\\\/\",\"name\":\"Roger&#039;s Site\",\"description\":\"My Life, My Notes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rogerrakestraw.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mindset Archives - Roger&#039;s Site","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rogerrakestraw.com\/index.php\/tag\/mindset\/","og_locale":"en_US","og_type":"article","og_title":"Mindset Archives - Roger&#039;s Site","og_url":"https:\/\/rogerrakestraw.com\/index.php\/tag\/mindset\/","og_site_name":"Roger&#039;s Site","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/rogerrakestraw.com\/index.php\/tag\/mindset\/","url":"https:\/\/rogerrakestraw.com\/index.php\/tag\/mindset\/","name":"Mindset Archives - Roger&#039;s Site","isPartOf":{"@id":"https:\/\/rogerrakestraw.com\/#website"},"breadcrumb":{"@id":"https:\/\/rogerrakestraw.com\/index.php\/tag\/mindset\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/rogerrakestraw.com\/index.php\/tag\/mindset\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rogerrakestraw.com\/"},{"@type":"ListItem","position":2,"name":"Mindset"}]},{"@type":"WebSite","@id":"https:\/\/rogerrakestraw.com\/#website","url":"https:\/\/rogerrakestraw.com\/","name":"Roger&#039;s Site","description":"My Life, My Notes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rogerrakestraw.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/rogerrakestraw.com\/index.php\/wp-json\/wp\/v2\/tags\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rogerrakestraw.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/rogerrakestraw.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/rogerrakestraw.com\/index.php\/wp-json\/wp\/v2\/posts?tags=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}